{"id":1114,"date":"2024-07-07T18:27:26","date_gmt":"2024-07-07T16:27:26","guid":{"rendered":"http:\/\/www.farum.it\/lectures\/?p=1114"},"modified":"2024-07-08T11:42:37","modified_gmt":"2024-07-08T09:42:37","slug":"mots-les-langages-du-politique-n-133-numero-thematique-la-republique-au-dela-du-slogan","status":"publish","type":"post","link":"https:\/\/www.farum.it\/lectures\/2024\/07\/07\/mots-les-langages-du-politique-n-133-numero-thematique-la-republique-au-dela-du-slogan\/","title":{"rendered":"Mots. Les langages du politique, n\u00b0 133, num\u00e9ro th\u00e9matique La R\u00e9publique au-del\u00e0 du slogan"},"content":{"rendered":"\n<p><em>Mots. Les langages du politique<\/em>, n\u00b0 133, num\u00e9ro th\u00e9matique<em> La R\u00e9publique au-del\u00e0 du slogan<\/em>, Dossier coordonn\u00e9 par Chlo\u00e9 GABORIAUX, C\u00e9dric PASSARD et Annabelle SEOANE, Lyon, ENS \u00c9ditions, novembre 2023, pp. 162.<\/p>\n\n\n\n<p>Le n\u00b0 133 de <em>Mots. Les langages du politique<\/em> est consacr\u00e9 au dossier <em>La R\u00e9publique au-del\u00e0 du slogan<\/em>. Dans l\u2019introduction,<em> Convoquer la R\u00e9publique, un argument-pi\u00e8ge&nbsp;?<\/em> (pp. 9-21), Chlo\u00e9 GABORIAUX, C\u00e9dric PASSARD et Annabelle SEOANE posent la R\u00e9publique comme objet privil\u00e9gi\u00e9&nbsp; d\u2019analyse en termes d\u2019appr\u00e9hension du terme \u00ab&nbsp;R\u00e9publique&nbsp;\u00bb en discours et d\u2019\u00e9volution de son sens avec le temps, en passant du renvoi \u00e0 l\u2019\u00c9tat et \u00e0 l\u2019organisation politique aux r\u00e9gimes non monarchiques. C\u2019est dans une vis\u00e9e de clarification que le pr\u00e9sent num\u00e9ro est con\u00e7u, abordant la R\u00e9publique tant \u00e0 partir de ses d\u00e9finitions philosophiques que par rapport aux conflits qu\u2019elle suscite. En vue de r\u00e9pondre \u00e0 la question initiale de la R\u00e9publique comme possible argument-pi\u00e8ge, le parcours qui est offert s\u2019int\u00e9resse \u00e0 deux volets. Le premier consiste \u00e0 montrer la mani\u00e8re dont l\u2019individu s\u2019\u00e9mancipe par le biais de son statut citoyen, concevant la libert\u00e9 comme non-domination mais en se r\u00e9f\u00e9rant \u00e9galement au poids des enjeux sociaux sur le r\u00e9publicanisme. Le second, quant \u00e0 lui, rappelle que, selon et en d\u00e9pit de la perspective adopt\u00e9e \u2013 le r\u00e9publicanisme en sociologie et en philosophie \u2013, le d\u00e9bat vis-\u00e0-vis de la R\u00e9publique est empreint des choix politiques du moment, opposant universalisme et communautarisme, par une appr\u00e9hension du r\u00e9publicanisme de la part de couleurs politiques diff\u00e9rentes et dans le but de viser des strat\u00e9gies politiques et de l\u00e9gitimer certains choix comme r\u00e9publicains et d\u2019autres comme non r\u00e9publicains. Dans ce m\u00eame d\u00e9bat politique, un r\u00f4le non n\u00e9gligeable est jou\u00e9 par la R\u00e9publique en termes m\u00e9tadiscursifs, en tant que levier pour disqualifier l\u2019adversaire politique \u00e0 gauche ainsi qu\u2019\u00e0 droite, mais, au fond, aussi comme levier pour convoquer un soubassement r\u00e9publicain comportant un consensus national autour d\u2019un enracinement culturel partag\u00e9. La R\u00e9publique repr\u00e9senterait alors un argument-pi\u00e8ge car faire appel \u00e0 la R\u00e9publique renvoie \u00e0 un positionnement oppositif pour le sujet locuteur \u00e0 partir de sa propre saisie du monde inscrite dans un consensus d\u00e9j\u00e0 \u00e9tabli tout comme \u00e0 une d\u00e9marche m\u00e9tadiscursive vis-\u00e0-vis de l\u2019objet cibl\u00e9. C\u2019est d\u2019un panorama h\u00e9t\u00e9rog\u00e8ne mais appuy\u00e9 une r\u00e9flexion commune autour de la R\u00e9publique qu\u2019il est question dans les cinq contributions du dossier, qui est compl\u00e9t\u00e9 par une section <em>Varia<\/em> (pp. 121-156) comportant deux contributions.<\/p>\n\n\n\n<p>Le premier article, r\u00e9dig\u00e9 par Jean Fabien SPITZ et introduit par Chlo\u00e9 GABORIAUX, <em>Domination \u00ab\u00a0structurelle\u00a0\u00bb\u00a0? Le r\u00e9publicanisme aux prises avec les in\u00e9galit\u00e9s socio-\u00e9conomiques<\/em> (pp. 23-38), pose la question du r\u00e9publicanisme et du n\u00e9o-r\u00e9publicanisme contemporain dans le contexte fran\u00e7ais, offrant une alternative lib\u00e9rale appuy\u00e9e sur une red\u00e9finition de la libert\u00e9 elle-m\u00eame et sur la d\u00e9fense des droits sociaux. Parmi les concepts qui sont \u00e9voqu\u00e9s pour tirer des le\u00e7ons du pass\u00e9 r\u00e9publicain, celui de \u00ab\u00a0domination\u00a0\u00bb s\u2019av\u00e8re \u00eatre op\u00e9ratoire par SPITZ pour rendre compte du travail de red\u00e9finition du n\u00e9o-r\u00e9publicanisme. Si, en effet, dans le cadre de ce courant, la libert\u00e9 est consid\u00e9r\u00e9e comme une absence de domination, et que la domination est con\u00e7ue en tant que domination personnelle, l\u2019id\u00e9e qui est d\u00e9velopp\u00e9e porte sur une domination d\u00e9pourvue d\u2019agent et li\u00e9e \u00e0 la soci\u00e9t\u00e9, donc \u00ab\u00a0structurelle\u00a0\u00bb, issue de la structure asym\u00e9trique des droits de propri\u00e9t\u00e9. Pour t\u00e9moigner de cette th\u00e8se, l\u2019auteur s\u2019appuie sur les travaux de Philip Pettit, d\u2019Alex Gourevitch et de Sharon Krause, relatifs \u00e0 la capacit\u00e9 du concept de \u00ab\u00a0r\u00e9publicanisme\u00a0\u00bb \u00e0 prendre en compte \u00e9galement les formes de non-libert\u00e9s qui affectent les individus dans le monde social et politique contemporain. C\u2019est pourquoi il examine les raisons de ce scepticisme et fournit deux suggestions op\u00e9ratoires, dont l\u2019une rel\u00e8ve d\u2019une \u00ab\u00a0domination sans agent\u00a0\u00bb, telle qu\u2019elle est pr\u00e9conis\u00e9e par Pettit, l\u2019autre attribue certaines formes de non-libert\u00e9s \u00e0 la mani\u00e8re dont les soci\u00e9t\u00e9s sont organis\u00e9es sur le plan social ou juridique, autrement dit des \u00ab\u00a0non-libert\u00e9s structurellement induites\u00a0\u00bb (p. 28). Pour justifier les n\u00e9gations de libert\u00e9s et les non-libert\u00e9s des soci\u00e9t\u00e9s contemporaines, ni l\u2019approche de Gourevitch concevant la domination comme non personnelle ni celle de Krause, consid\u00e9rant la domination comme le r\u00e9sultat de structures de pens\u00e9e et d\u2019action, ne sont retenues. La possibilit\u00e9 de parler de \u00ab\u00a0domination structurelle\u00a0\u00bb pour expliquer les in\u00e9galit\u00e9s socio\u00e9conomiques du r\u00e9publicanisme des soci\u00e9t\u00e9s contemporaines reste alors une question ouverte, pour laquelle l\u2019auteur renvoie au concept de \u00ab\u00a0responsabilit\u00e9\u00a0\u00bb\u00a0: l\u2019enjeu ne rel\u00e8ve pas du comportement des agents, mais de la structure qui d\u00e9termine leurs actions.<\/p>\n\n\n\n<p>Le r\u00e9publicanisme fran\u00e7ais et la libert\u00e9 citoyenne sur la sc\u00e8ne politique et dans le contexte socio\u00e9conomique sont \u00e9galement vis\u00e9s par Johan GIRY et S\u00e9bastien URBANSKI, qui les abordent sous la perspective de l\u2019\u00c9cole fran\u00e7aise de sociologie (<em>La sociologie fran\u00e7aise face au probl\u00e8me de l\u2019universalisme r\u00e9publicain. Essai de typologie des <\/em>motifs <em>de la dispute<\/em>, pp. 39-60). En vue d\u2019examiner le d\u00e9bat sociologique li\u00e9 \u00e0 la publication des deux ouvrages <em>D\u00e9ni des cultures<\/em> (Lagrange 2010) et <em>Race et sciences sociales <\/em>(Beaud, Noiriel 2021), les auteurs interrogent le concept d\u2019\u00ab&nbsp;universalisme r\u00e9publicain&nbsp;\u00bb dans une perspective durkheimienne \u00e0 l\u2019appui d\u2019un corpus de textes collect\u00e9s entre 2010 et 2023. Ils signalent que les discussions en cours rel\u00e8veraient de l\u2019acc\u00e9l\u00e9ration de la division du travail social et de l\u2019individualisme croissant dans la conscience collective des soci\u00e9t\u00e9s modernes. Leur analyse montre non seulement une politisation ext\u00e9rieure de la sociologie \u00e0 l\u2019\u00e9gard de ce d\u00e9bat id\u00e9ologique, mais aussi l\u2019identification de trois \u00ab&nbsp;motifs&nbsp;\u00bb distincts et antagonistes \u2013 lib\u00e9ral, conservateur et socialiste \u2013 de la R\u00e9publique aupr\u00e8s des disputes sociologiques, dont le but est de faire agir mais aussi d\u2019expliquer le probl\u00e8me qui est pos\u00e9. Dans cette tripartition, emprunt\u00e9e \u00e0 Karl Mannheim (1929), le motif lib\u00e9ral consid\u00e8re l\u2019universalisme r\u00e9publicain comme une minimisation des diff\u00e9rences de statuts, o\u00f9 les fronti\u00e8res entre individus et groupes sont attribu\u00e9es \u00e0 la division du travail social. Son succ\u00e8s a engendr\u00e9 l\u2019apparition du motif conservateur, par rapport auquel la d\u00e9fense de la soci\u00e9t\u00e9 requiert une r\u00e9affirmation des diff\u00e9rences de statuts et des fronti\u00e8res, ce qui participe du mouvement d\u00e9mocratique dans une soci\u00e9t\u00e9 moderne. Si ce mod\u00e8le est minoritaire, il permet quand m\u00eame de faire r\u00e9fl\u00e9chir sur les tensions internes aux revendications qui sont montr\u00e9es. D\u2019o\u00f9 l\u2019\u00e9mergence d\u2019un motif socialiste en tant que tiers manquant, permettant aussi bien de reconna\u00eetre l\u2019importance des diff\u00e9rences de statuts et des fronti\u00e8res li\u00e9es \u00e0 la division du travail dans la soci\u00e9t\u00e9 fran\u00e7aise que d\u2019avoir tendance \u00e0 ignorer les solidarit\u00e9s objectives qui s\u2019ensuivent. Les conclusions des auteurs confirment que la dispute autour de l\u2019universalisme r\u00e9publicain fran\u00e7ais doit \u00eatre rapport\u00e9e aux termes d\u2019\u00ab&nbsp;individu&nbsp;\u00bb, de \u00ab&nbsp;groupe&nbsp;\u00bb et de \u00ab&nbsp;nation&nbsp;\u00bb, qui sont inh\u00e9rents aux trois motifs. GIRY et URBANSKI pr\u00e9conisent alors un socialisme sociologique comme voie pour atteindre un universalisme r\u00e9publicain de pr\u00e9servation du culte moderne de l\u2019individu et de ses solidarit\u00e9s r\u00e9elles.<\/p>\n\n\n\n<p>Dans une perspective d\u2019analyse du discours, Damien DEIAS examine les strat\u00e9gies politiques par lesquelles certaines positions, l\u00e9gitim\u00e9es comme r\u00e9publicaines, s\u2019opposent \u00e0 des positions qualifi\u00e9es de non-r\u00e9publicaines (<em>La R\u00e9publique au-del\u00e0 d\u2019une <\/em>petite phrase&nbsp;<em>: r\u00e9ception de l\u2019\u00e9nonc\u00e9 \u00ab&nbsp;La R\u00e9publique, c\u2019est moi&nbsp;!&nbsp;\u00bb<\/em>, pp. 61-78). Son point de d\u00e9part est repr\u00e9sent\u00e9 par la \u00ab&nbsp;petite phrase&nbsp;\u00bb \u00ab La R\u00e9publique, c\u2019est moi ! \u00bb, prononc\u00e9e par Jean-Luc M\u00e9lenchon le 16 octobre 2018 lors d\u2019une perquisition au si\u00e8ge de La France insoumise. C\u2019est la circulation m\u00e9diatico-discursive de cette \u00ab&nbsp;petite phrase&nbsp;\u00bb, dont la reproduction m\u00e9diatique est tr\u00e8s \u00e9lev\u00e9e, au point de devenir une \u00ab&nbsp;panaphorisation&nbsp;\u00bb, qui est vis\u00e9e par l\u2019auteur \u00e0 partir du corpus de presse nationale et locale fran\u00e7aise d\u2019<em>Europresse<\/em>. Comme toute \u00ab&nbsp;aphorisation&nbsp;\u00bb, cette \u00ab&nbsp;petite phrase&nbsp;\u00bb, qui s\u2019av\u00e8re \u00eatre \u00e9galement un \u00ab&nbsp;<em>snowclone<\/em>&nbsp;\u00bb \u2013 par rapport \u00e0 \u00ab&nbsp;L\u2019\u00c9tat, c\u2019est moi&nbsp;!&nbsp;\u00bb, attribu\u00e9 \u00e0 Louis XIV \u2013, est d\u00e9contextualis\u00e9e au point d\u2019identifier la personnalit\u00e9 de Jean-Luc M\u00e9lenchon. DEIAS s\u2019attarde ainsi sur les effets produits par la panaphorisation pour mettre en \u00e9vidence, entre autres, que l\u2019emploi de cette petite phrase par la presse souligne des probl\u00e8mes au niveau des \u00e9thos. Les \u00e9thos qu\u2019elle sous-tend ne correspondent en effet pas \u00e0 la posture attendue par un sujet politique, d\u2019autant plus qu\u2019ils sont en contradiction avec l\u2019ordre r\u00e9publicain. Cette contradiction, largement relay\u00e9e par la presse, rel\u00e8ve de l\u2019inad\u00e9quation entre l\u2019\u00e9thos exp\u00e9rientiel de Jean-Luc M\u00e9lenchon pendant la perquisition et l\u2019\u00e9thos id\u00e9ologique qu\u2019il affiche dans ses discours, notamment par rapport \u00e0 l\u2019autoritarisme de la petite phrase et \u00e0 sa proposition de cr\u00e9er la VI<sup>e<\/sup> R\u00e9publique, voire \u00e0 l\u2019\u00e9thos cat\u00e9goriel renvoyant \u00e0 l\u2019attitude qui serait attendue par la figure de candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle et \u00e0 celle d\u2019\u00e9lu.<\/p>\n\n\n\n<p>L\u2019analyse du discours politique fait \u00e9galement l\u2019objet de la contribution de Laura CALABRESE et Sol MONTERO, qui pr\u00e9sentent une comparaison entre la France et l\u2019Argentine lors des \u00e9lections pr\u00e9sidentielles de 2022 et de 2019, respectivement (<em>Invoquer la R\u00e9publique. Usages consensuels et pol\u00e9miques dans le discours politique en France et en Argentine<\/em>, pp. 79-97). Le concept sociopolitique de \u00ab&nbsp;r\u00e9publique\/<em>rep\u00fablica<\/em>&nbsp;\u00bb et son travail m\u00e9tadiscursif comme levier argumentatif pour (dis)qualifier l\u2019adversaire politique, et pour l\u2019\u00e9loigner de la R\u00e9publique et des valeurs r\u00e9publicaines, sont explor\u00e9s par les deux auteures \u00e0 partir d\u2019un corpus de 400 tweets collect\u00e9s pendant la campagne \u00e9lectorale pour la pr\u00e9sidentielle dans les deux pays. L\u2019usage du lex\u00e8me montre des variations s\u00e9mantico-r\u00e9f\u00e9rentielles importantes. Si un consensus semble concerner sa d\u00e9finition intentionnelle de d\u00e9signation d\u2019un r\u00e9gime d\u00e9mocratique non h\u00e9r\u00e9ditaire \u00e9lu, c\u2019est dans les d\u00e9finitions extensionnelles qu\u2019\u00e9mergent les distinctions principales. Celles-ci se d\u00e9ploient par le biais des personnes candidates, des phrases d\u00e9nominatives et de leurs co-occurrents, mais aussi par des id\u00e9ologies politiques diverses, tandis que les emplois discursifs du terme argentin sont aussi bien pol\u00e9miques que polarisants, \u00e9tant donn\u00e9 les clivages entre gauche et droite, mais aussi entre p\u00e9ronisme et anti-p\u00e9ronisme, voire entre populistes et antipopulistes. Les auteures constatent ainsi que le r\u00e9publicanisme est m\u00eame li\u00e9 \u00e0 des discours d\u2019extr\u00eame droite par un \u00e9largissement du concept qui permet d\u2019y inclure \u00e9galement des id\u00e9ologies conservatrices. Il \u00e9merge que, contrairement \u00e0 la France, ce concept ne s\u2019av\u00e8re pas \u00eatre consensuel en Argentine, dont l\u2019emploi repr\u00e9sente un positionnement de la personne qui l\u2019\u00e9nonce. Les conclusions de CALABRESE et de MONTERO soulignent donc l\u2019instabilit\u00e9 r\u00e9f\u00e9rentielle de la notion examin\u00e9e dans les deux contextes politiques \u00e9tudi\u00e9s.<\/p>\n\n\n\n<p>Le discours politique et l\u2019argumentation dans le discours font \u00e9galement l\u2019objet de la derni\u00e8re contribution du dossier, Rzeczpospolita<em>, la <\/em>res publica<em> des valeurs<\/em> (pp. 99-118), consacr\u00e9e aux discours des Pr\u00e9sidents de la Troisi\u00e8me R\u00e9publique de Pologne, commenc\u00e9e en 1989. Jolanta DYONIZIAK et Ewa PIROGOWSKA tracent le parcours \u00e9tymologique et historique de la \u00ab&nbsp;<em>Rzeczpospolita Polska<\/em>&nbsp;\u00bb, \u00e0 savoir la <em>res publica <\/em>polonaise, qui tire ses origines du XVI<sup>e <\/sup>si\u00e8cle et qui a ensuite \u00e9t\u00e9 adopt\u00e9e dans le cadre de la Premi\u00e8re R\u00e9publique, de la Deuxi\u00e8me R\u00e9publique et lors du r\u00e9gime r\u00e9publicain actuel. Ce mot se r\u00e9v\u00e8le ainsi riche en connotations, du fait d\u2019\u00eatre li\u00e9 \u00e0 la m\u00e9moire collective de la nation, qu\u2019il doit activer m\u00eame \u00e0 l\u2019\u00e9gard de la population. Ce sont ainsi les configurations s\u00e9mantico-argumentatives de ce nom qui sont abord\u00e9es par les auteures \u00e0 partir d\u2019une \u00e9tude qualitative et synchronique, pour souligner que les Pr\u00e9sidents de la Troisi\u00e8me R\u00e9publique de Pologne s\u2019efforcent, dans leurs allocutions publi\u00e9es sur le site web du gouvernement polonais, \u00e0 capter l\u2019adh\u00e9sion de leur auditoire par l\u2019appui sur les valeurs qui sont le propre du contexte politique polonais. L\u2019\u00e9tude porte sur les \u00e9l\u00e9ments qui fa\u00e7onnent l\u2019identit\u00e9 discursive de la <em>Rzeczpospolita<\/em> \u00e0 partir de l\u2019approche argumentative de Perelman et Olbrechts-Tyteca (2008). En particulier, les auteures examinent les lieux, en tant que pr\u00e9misses de l\u2019argumentation, relevant des valeurs qui \u00e9mergent des discours des Pr\u00e9sidents de la R\u00e9publique. Sont ainsi mises en \u00e9vidence la valeur de communaut\u00e9, celle d\u2019ind\u00e9pendance et des sujets qui luttent pour la manifester, celle de tol\u00e9rance envers d\u2019autres cultures, celle de v\u00e9rit\u00e9 historique dans le cadre des enjeux m\u00e9moriels, celle de respect \u00e0 l\u2019\u00e9gard de la tradition, celles de progression et de succ\u00e8s vis-\u00e0-vis de la patrie. Au terme de ce parcours autour du concept de \u00ab&nbsp;<em>Rzeczpospolita<\/em>&nbsp;\u00bb, les auteures confirment que celui-ci est inh\u00e9rent \u00e0 la citoyennet\u00e9 polonaise et qu\u2019il montre une longue tradition discursive \u00e0 vis\u00e9e argumentative pour f\u00e9d\u00e9rer l\u2019auditoire autour de valeurs partag\u00e9es.<\/p>\n\n\n\n<p>Ce num\u00e9ro th\u00e9matique permet de concevoir la R\u00e9publique comme un projet d\u2019\u00e9mancipation de l\u2019individu par le biais de la citoyennet\u00e9, l\u00e0 o\u00f9 celui-ci garde son individualit\u00e9 tout en \u00e9tant impliqu\u00e9 dans la sph\u00e8re sociale et politique. Les r\u00e9flexions d\u00e9velopp\u00e9es \u00e0 partir des cinq contributions du dossier soulignent donc, selon les perspectives nationales \u00e9tudi\u00e9es, les couches de sens qui rel\u00e8vent de l\u2019appr\u00e9hension de la R\u00e9publique de la part des enjeux politiques de chaque pays <em>via <\/em>les langages \u00e9nonc\u00e9s comme r\u00e9publicains.<\/p>\n\n\n\n<p>Les deux derni\u00e8res contributions de ce num\u00e9ro de <em>Mots. Les langages du politique<\/em> sont r\u00e9unies dans la section <em>Varia<\/em> (pp. 119-156). La premi\u00e8re d\u2019entre elles, <em>Du menu \u00ab&nbsp;la\u00efque&nbsp;\u00bb au menu \u00ab&nbsp;\u00e9colo&nbsp;\u00bb. Analyse de la couverture m\u00e9diatique autour de l\u2019introduction de menus v\u00e9g\u00e9tariens dans les cantines scolaires<\/em> (pp. 121-140), propose une analyse m\u00e9diatique longitudinale sur corpus sur l\u2019introduction du menu v\u00e9g\u00e9tarien dans les cantines scolaires de diverses villes fran\u00e7aises (lois Egalim de 2018 et 2021). Aude CHAUVIAT et Cl\u00e9mentine HUGOL-GENTIAL s\u2019int\u00e9ressent \u00e0 la couverture m\u00e9diatique que ce sujet a re\u00e7u dans la presse nationale et r\u00e9gionale (corpus <em>Europresse<\/em>) \u00e0 partir des titres les plus lus entre 2000 et 2022, pour souligner sa m\u00e9diatisation, notamment les formes de r\u00e9sistance affich\u00e9es par la politique et les enjeux de la \u00ab&nbsp;transition alimentaire&nbsp;\u00bb. Apr\u00e8s avoir pr\u00e9sent\u00e9 le contexte de ce d\u00e9bat soci\u00e9tal, culturel, politique et donc m\u00e9diatique, les auteures caract\u00e9risent le type de discours \u00e9nonc\u00e9, son contenu informationnel et ses cadres m\u00e9diatiques dominants \u00e0 l\u2019appui du logiciel <em>IraMuTeQ<\/em>. Par le biais d\u2019une perspective diachronique, elles se penchent sur les \u00ab&nbsp;pics&nbsp;\u00bb de m\u00e9diatisation observables par rapport \u00e0 la p\u00e9riode examin\u00e9e, sur l\u2019\u00e9volution des repr\u00e9sentations politiques, publiques et soci\u00e9tales associ\u00e9es au menu v\u00e9g\u00e9tarien \u00e0 la cantine, sur les univers discursifs et lexicaux concurrents qui sont mobilis\u00e9s autour de ce sujet, sur les cas de sous-repr\u00e9sentation de certains acteurs dans cette affaire, mais aussi sur un traitement diff\u00e9renci\u00e9 selon les journaux pris en compte. Il \u00e9merge que le menu v\u00e9g\u00e9tarien dans les cantines devient pour la presse un pr\u00e9texte pour aborder des questions soci\u00e9tales et politiques majeures, parmi lesquelles l\u2019\u00e9ducation alimentaire, la la\u00efcit\u00e9, la religion et le r\u00f4le des pouvoirs publics.<\/p>\n\n\n\n<p>Enfin, la contribution de Wilfried SEGUE aborde le discours comm\u00e9moratif d\u2019Emmanuel Macron lors du bicentenaire de la mort de Napol\u00e9on Bonaparte, le 5 mai 2021, notamment le dispositif discursif qui \u00e9merge de l\u2019allocution, presque in\u00e9dite, prononc\u00e9e par le Pr\u00e9sident de la R\u00e9publique \u00e0 cet \u00e9gard (<em>Le souffle comm\u00e9moratif&nbsp;: ce que Napol\u00e9on 1<sup>er<\/sup> nous dit d\u2019Emmanuel Macron<\/em>, pp. 141-156). Par le biais d\u2019une perspective transdisciplinaire combinant l\u2019analyse du discours et l\u2019analyse stylistique, l\u2019auteur s\u2019appuie sur les notions de \u00ab&nbsp;r\u00e9cit national&nbsp;\u00bb et d\u2019\u00ab&nbsp;identicit\u00e9&nbsp;\u00bb <em>via <\/em>celle de \u00ab&nbsp;souffle&nbsp;\u00bb, emprunt\u00e9e \u00e0 l\u2019analyse de la cadence par masses syntaxiques de Molini\u00e9 (2011). Il explore d\u2019abord la c\u00e9l\u00e9bration de Napol\u00e9on \u00e0 partir des mots prononc\u00e9s par E. Macron dans son discours solennel pour ensuite placer le \u00ab&nbsp;souffle&nbsp;\u00bb li\u00e9 au discours comm\u00e9moratif dans le cadre du rythme et de l\u2019argumentation. Deux dynamiques discursives sont d\u00e9velopp\u00e9es en m\u00eame temps par le Pr\u00e9sident de la R\u00e9publique&nbsp;: l\u2019une concerne la mani\u00e8re d\u2019articuler l\u2019histoire dans le r\u00e9cit national, l\u2019autre la fa\u00e7on de r\u00e9orienter le mythe et sa puissance \u00e9vocatrice dans la m\u00e9moire collective. L\u2019analyse conduite par SEGUE montre que la prise de parole d\u2019E. Macron se situe dans le cadre du r\u00e9cit national, retravaillant l\u2019imagerie de la nation et l\u2019identifiant dans le mythe, l\u00e0 o\u00f9 le propos pr\u00e9sidentiel retourne l\u2019hommage en un discours explicatif et argumentatif sur l\u2019imagerie napol\u00e9onienne dans le r\u00e9cit national. De l\u2019autre c\u00f4t\u00e9, son discours concourt \u00e0 une politique mythologique pour ce qui est de l\u2019hommage qui est rendu \u00e0 Napol\u00e9on, sous-tendant une d\u00e9finition univoque de l\u2019identicit\u00e9 fran\u00e7aise. Il en r\u00e9sulte une inspiration citoyenne appuy\u00e9e sur un dispositif par lequel E. Macron r\u00e9ussit \u00e0 franchir m\u00eame les ombres de la R\u00e9publique par un sens li\u00e9 \u00e0 la grandeur du r\u00e9cit et de la nation.<\/p>\n\n\n\n<p>[Alida M. SILLETTI]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mots. Les langages du politique, n\u00b0 133, num\u00e9ro th\u00e9matique La R\u00e9publique au-del\u00e0 du slogan, Dossier coordonn\u00e9 par Chlo\u00e9 GABORIAUX, C\u00e9dric PASSARD et Annabelle SEOANE, Lyon, ENS \u00c9ditions, novembre 2023, pp. 162. Le n\u00b0 133 de Mots. Les langages du politique est consacr\u00e9 au dossier La R\u00e9publique au-del\u00e0 du slogan. Dans l\u2019introduction, Convoquer la R\u00e9publique, un\u2026 <span class=\"read-more\"><a href=\"https:\/\/www.farum.it\/lectures\/2024\/07\/07\/mots-les-langages-du-politique-n-133-numero-thematique-la-republique-au-dela-du-slogan\/\">Leggi tutto &raquo;<\/a><\/span><\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-1114","post","type-post","status-publish","format-standard","hentry","category-n52"],"_links":{"self":[{"href":"https:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/posts\/1114"}],"collection":[{"href":"https:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/comments?post=1114"}],"version-history":[{"count":3,"href":"https:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/posts\/1114\/revisions"}],"predecessor-version":[{"id":1160,"href":"https:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/posts\/1114\/revisions\/1160"}],"wp:attachment":[{"href":"https:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/media?parent=1114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/categories?post=1114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/tags?post=1114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}