{"id":277,"date":"2021-06-29T16:24:55","date_gmt":"2021-06-29T14:24:55","guid":{"rendered":"http:\/\/www.farum.it\/lectures\/?p=277"},"modified":"2021-07-11T14:42:11","modified_gmt":"2021-07-11T12:42:11","slug":"lorella-sini-rosa-cetro-eds-fake-news-rumeurs-intox-strategies-et-visees-discursives-de-la-desinformation-paris-lharmattan-2020-p-326","status":"publish","type":"post","link":"http:\/\/www.farum.it\/lectures\/2021\/06\/29\/lorella-sini-rosa-cetro-eds-fake-news-rumeurs-intox-strategies-et-visees-discursives-de-la-desinformation-paris-lharmattan-2020-p-326\/","title":{"rendered":"Lorella SINI, Rosa CETRO (\u00e9ds.), FAKE NEWS RUMEURS, INTOX&#8230; Strat\u00e9gies et vis\u00e9es discursives de la d\u00e9sinformation, Paris, L&#8217;Harmattan, 2020, p. 326."},"content":{"rendered":"\n<p>Rosa Cetro et Lorella Sini sont les deux coordinatrices du volume <em>Fake news, rumeurs, intox\u2026 Strat\u00e9gies et vis\u00e9es discursives de la d\u00e9sinformation<\/em> paru chez L\u2019Harmattan et publi\u00e9 dans la collection <em>Humanit\u00e9s Num\u00e9riques<\/em>, avec le soutien de plusieurs organismes\u00a0: LIDILEM<strong>, <\/strong>Universit\u00e9 Franco-Italienne<strong>, <\/strong>Universit\u00e0 di Pisa \u2013 Dipartimento di Filologia, Letteratura e Linguistica et Do.Ri.F Universit\u00e0. Les articles du volume sont r\u00e9partis en trois sections, chacune d\u2019elles ayant comme th\u00e9matique une approche diff\u00e9rente face \u00e0 la prolif\u00e9ration du ph\u00e9nom\u00e8ne m\u00e9diatique des <em>fake news <\/em>qui a engendr\u00e9 des r\u00e9actions de la part de plusieurs cat\u00e9gories socio-professionnelles.<\/p>\n\n\n\n<p>Les sept contributions <strong>de la premi\u00e8re partie<\/strong> du volume intitul\u00e9e <em>Enjeux sociaux, discours et contre-discours<\/em> se proposent de d\u00e9monter les m\u00e9canismes cognitifs et les proc\u00e9d\u00e9s linguistico-discursifs des <em>fake news<\/em> afin de tirer un signal d\u2019alarme que cette probl\u00e9matique touche non seulement les journalistes, mais aussi les acteurs produisant les informations et les internautes, qui doivent \u00eatre sensibilis\u00e9s \u00e0 la v\u00e9rification des contenus transmis par autrui et \u00e0 l\u2019importance d\u2019une conscience \u00e0 la fois critique et \u00e9thique.<\/p>\n\n\n\n<p>Le premier article est consacr\u00e9 par <strong>Julien Longhi<\/strong> \u00e0 l\u2019interrogation sur le processus d\u2019id\u00e9ologisation<em> &#8211; S\u00e9mantique du discours et processus d\u2019id\u00e9ologisation. Comment cartographier l\u2019information et caract\u00e9riser la d\u00e9sinformation<\/em> ? En fait, l\u2019auteur propose une approche discursive des <em>fake news<\/em> par la prise en charge de deux aspects essentiels : la contextualisation et la mat\u00e9rialit\u00e9 lexicale. L\u2019analyse du discours acquiert ainsi un r\u00f4le primordial dans le processus de cartographier l\u2019information \u00e0 partir de la mat\u00e9rialit\u00e9 linguistique et discursive des informations partag\u00e9es par les deux p\u00f4les du message&nbsp;: \u00e9metteur et r\u00e9cepteur.<\/p>\n\n\n\n<p>Prenant comme point de d\u00e9part la question des <em>fake news <\/em>sur la toxicit\u00e9 du <em>Roundup<\/em> et de sa mol\u00e9cule active &#8211; le <em>glyphosate<\/em>, l\u2019article de<strong> Fran\u00e7ois Allard-Huver<\/strong> (<em>Discours, intox et contre-discours en controverse scientifique : l\u2019affaire des \u00abPortier Papers\u00bb<\/em>) pr\u00e9sente les strat\u00e9gies suivies par les acteurs impliqu\u00e9s dans la production des discours et des contre-discours, d\u2019une part, et dans la d\u00e9nonciation des fausses nouvelles, d\u2019autre part. En effet, cette \u00e9tude nous fait part d\u2019une controverse scientifique m\u00e9diatique provoquant des pol\u00e9miques entre les promoteurs de la<br>campagne de communication et les enqu\u00eateurs journalistiques s\u2019appuyant sur des r\u00e9sultats d\u2019expertises.<\/p>\n\n\n\n<p>\u00c0 partir d\u2019un projet d\u2019exploitation de gaz de charbon (<em>Coal bed methane<\/em>), <strong>Marieke Stein<\/strong> (<em>Comment le faux s\u2019impose dans le discours dominant : les relais institutionnels de la d\u00e9sinformation autour d\u2019une controverse environnementale<\/em>) fait l\u2019analyse du discours dominant afin de montrer comment la presse et les discours institutionnels contribuent \u00e0 v\u00e9hiculer de fausses informations dans l\u2019espace public. En fait, il s\u2019agit du processus de res\u00e9mantisation et de renomination de l\u2019expression <em>gaz de couche<\/em>, remplac\u00e9e par le vocable <em>grisou <\/em>(charg\u00e9 de sens dans la m\u00e9moire collective) pour faire admettre des prospections invasives et polluantes.<\/p>\n\n\n\n<p>Une autre piste d\u2019action contre les <em>fake news<\/em> est propos\u00e9e par <strong>Dominique Dias<\/strong> (<em>Le fact-checking: un nouveau genre textuel pour lutter contre la d\u00e9sinformation ?)<\/em> qui d\u00e9finit le <em>fact-checking<\/em> comme ph\u00e9nom\u00e8ne m\u00e9diatique, relevant de la cat\u00e9gorie des m\u00e9tatextes par des commentaires d\u2019autres textes\/\u00e9nonc\u00e9s et ayant comme principales caract\u00e9ristiques linguistiques des phras\u00e9ologies (\u00abce que je dis est vrai \u00bb), des routines journalistiques ou des constructions argumentatives st\u00e9r\u00e9otyp\u00e9es.<\/p>\n\n\n\n<p><strong>Silvia Modena<\/strong> (\u00ab&nbsp;<em>Fred se m\u00e9fie des fausses infos&nbsp;\u00bb&nbsp;<\/em>: <em>une bande dessin\u00e9e pour \u00ab&nbsp;verifier&nbsp;\u00bb les informations<\/em>) nous pr\u00e9sente un autre cas de figure, celui de la bande dessin\u00e9e en tant que contre-discours p\u00e9dagogique cens\u00e9 neutraliser les infox chez les jeunes. L\u2019auteure consid\u00e8re que les quatre types d\u2019argument (\u00ab&nbsp;l\u2019argument d\u2019autorit\u00e9&nbsp;\u00bb, \u00ab&nbsp;l\u2019argument de direction&nbsp;\u00bb, \u00ab&nbsp;l\u2019argument du consensus&nbsp;\u00bb et \u00ab&nbsp;la question rh\u00e9torique&nbsp;\u00bb) lui permettent d\u2019affirmer que le dialogue fictif de cette bande dessin\u00e9e a pour but d\u2019interrompre le flux de fausses informations par la mise en place de deux typologies de voix : une voix \u00e0 la fois experte dans les r\u00e9citatifs, mais aussi amicale et une instance \u00e9nonciative \u00abna\u00efve\u00bb, celle de l\u2019internaute Fred qu\u2019il faut \u00ab\u00e9duquer \u00bb.<\/p>\n\n\n\n<p>Partant d\u2019un corpus de messages post\u00e9s par des patients atteints de cancer sur des forums de discussion, <strong>Val\u00e9rie Delavigne<\/strong> (<em>Forums et infox<\/em>) fait une analyse minutieuse de la nature sp\u00e9cialis\u00e9e de l\u2019information m\u00e9dicale autour de la th\u00e9matique du cancer dans les forums de discussion comme objet de choix pour explorer les nouveaux modes de diffusion et de circulation des informations conduisant \u00e0 \u00ab&nbsp;une sorte de d\u00e9sacralisation du savoir m\u00e9dical&nbsp;\u00bb qui reste hautement sp\u00e9cialis\u00e9, tout en paraissant particuli\u00e8rement adapt\u00e9 et pertinent pour les patients.<\/p>\n\n\n\n<p>Dans <em>Fake news et \u00e9conomie. Un nouvel enjeu pour les entreprises<\/em>,<strong> Alessandra Rollo<\/strong> nous donne deux exemples embl\u00e9matiques de <em>fake news <\/em>qui ont frapp\u00e9 des marques fran\u00e7aises : le faux communiqu\u00e9 de presse qui a fait chuter l\u2019action du colosse boursier <em>Vinci<\/em> en novembre 2016 et la rumeur qui a touch\u00e9 la compagnie a\u00e9rienne <em>Air France<\/em> concernant l\u2019augmentation abusive de ses tarifs apr\u00e8s le passage de l\u2019ouragan Irma aux Cara\u00efbes en septembre 2017. L\u2019auteure met en exergue la rapidit\u00e9 de propagation des fausses informations sur les r\u00e9seaux sociaux avec des r\u00e9percussions n\u00e9fastes pour ces deux compagnies.<\/p>\n\n\n\n<p>Les contributions de <strong>la deuxi\u00e8me partie<\/strong> intitul\u00e9e <em>De la propagande aux fake news<\/em> prolongent le d\u00e9bat entre propagande et information fallacieuse dans les domaines de la politique et de la religion. Se proposant d\u2019examiner comment l\u2019expression <em>fake news <\/em>\u00e9merge et se comporte dans un discours anti-m\u00e9dias, <strong>Laura Calabrese, Pascal Froissart <\/strong>et<strong> Jeoffrey Gaspard<\/strong> (<em>De la propagande aux fake news Trump to the media: Fake you!<\/em>) font une analyse lexicom\u00e9trique des occurrences de cette expression dans les tweets du compte <em>@realDonaldTrump<\/em> repr\u00e9sentant trois \u00e9nonciateurs diff\u00e9rents (Trump\u00a0 homme d\u2019affaires, Trump candidat et Trump pr\u00e9sident) dans\u00a0 le but de mettre en exergue sa contribution \u00e0 la d\u00e9cr\u00e9dibilisation des medias hostiles \u00e0 Trump, d\u2019une part, et le rejet des accusations de d\u00e9sinformation de la campagne pr\u00e9sidentielle, d\u2019autre part.\u00a0<\/p>\n\n\n\n<p><strong>M\u00e9lanie Gantier<\/strong> (<em>La strat\u00e9gie de communication de Donald Trump sur Twitter : comment les \u00e9motions ont pris le pouvoir<\/em>) consacre son article \u00e0 l\u2019analyse des termes d\u2019affect ou des termes d\u2019\u00e9motion identifi\u00e9s sous forme de m\u00e9taphores employ\u00e9es dans les tweets de la campagne \u00e9lectorale de Donald Trump pour purifier le pays par la mise en garde contre le flot de l\u2019immigration. Une autre strat\u00e9gie de communication consiste dans l\u2019usage de l\u2019exclamation, de m\u00eame que du commentaire \u00e9motionnel <em>so sad!, very sad <\/em>ou <em>sad! <\/em>dans les tweets qui sont retweet\u00e9s par les soutiens de Donald Trump dans le but d\u2019augmenter l\u2019ampleur de l\u2019audience.<\/p>\n\n\n\n<p>Dans leur \u00e9tude sur les discours de propagande et de radicalisation diffus\u00e9s dans la revue <em>Dar-al-Islam, <\/em><strong>Nolwenn Lorenzi Bailly <\/strong>et<strong> Claudine Mo\u00efse (<\/strong><em>DAR AL-ISLAM Propagande, manipulation et malinformation<\/em>) introduisent des notions interm\u00e9diaires&nbsp; telles&nbsp; que <em>m\u00e9sinformation,&nbsp; malinformation, d\u00e9sinformation<\/em>. L\u2019article propose une r\u00e9flexion autour des proc\u00e9d\u00e9s discursifs qui se manifestent dans le discours de propagande et le discours id\u00e9ologique dans les rubriques du magazine <em>Dar Al-Islam<\/em>. Il s\u2019agit de la construction d\u2019une figure d\u2019autorit\u00e9 dont le but de faire adh\u00e9rer le plus grand nombre de lecteurs \u00e0 l\u2019id\u00e9ologie meurtri\u00e8re.<\/p>\n\n\n\n<p>Les Bulletins de guerre de l\u2019Alliance fran\u00e7aise de Paris (1914-1918) font l\u2019objet d\u2019\u00e9tude d\u2019<strong>Alice H\u00e9l\u00e8ne Burrows<\/strong> (<em>De la propagande \u00e0 la d\u00e9sinformation : les strat\u00e9gies discursives de mondialisation du conflit<\/em>) qui se propose de surprendre \u00ab&nbsp;le glissement&nbsp;\u00bb de la revue vers un discours complotiste de d\u00e9sinformation utilitariste qui marque une rupture discursive importante dans le travail de propagande men\u00e9 par l\u2019association. Une attention particuli\u00e8re est accord\u00e9e \u00e0 la valeur des objets discursifs historiques qui sont analys\u00e9s selon deux \u00e9chelles d\u2019observation&nbsp;: l\u2019unit\u00e9 temporelle et l\u2019unit\u00e9 g\u00e9ographique.<\/p>\n\n\n\n<p><strong>Alida Maria Silletti<\/strong> (<em>Les donn\u00e9es chiffr\u00e9es dans les tracts du FN\/RN sur l\u2019immigration (2008-2019) : une forme d\u2019\u00ab intox \u00bb ?<\/em>) \u00e9tudie la mani\u00e8re dont la d\u00e9contextualisation syst\u00e9matique ou l\u2019effacement des sources \u00e9nonciatives op\u00e8re un d\u00e9tournement d\u2019informations par simplification et par dramatisation afin d\u2019obtenir l\u2019adh\u00e9sion des lecteurs par rapport \u00e0 l\u2019immigration\u00a0: <em>\u00e9quations islam-immigration, immigration- violence\/ins\u00e9curit\u00e9, immigration-ch\u00f4mage, immigration-Europe, immigr\u00e9 \u00e9conomique-r\u00e9fugi\u00e9\/demandeur d\u2019asile, entre autres<\/em>. L\u2019article confirme, en conclusion, que les\u00a0 chiffres relatifs \u00e0 l\u2019immigration ne sont pas strictement quantifiables car, selon l\u2019auteure, \u00ab\u00a0c\u2019est souvent sa source qui porte atteinte \u00e0 sa l\u00e9gitimit\u00e9\u00a0\u00bb.<\/p>\n\n\n\n<p>\u00c0 travers les diff\u00e9rentes modalit\u00e9s aspectuelles de la formule \u00ab cinqui\u00e8me mandat\u00bb, <strong>Kamila Oulebsir-Oukil<\/strong> (<em>Cinqui\u00e8me mandat pr\u00e9sidentiel en Alg\u00e9rie : le (contre) discours de la rumeur<\/em>) montre comment une rumeur se transforme en information officieuse puis en information attest\u00e9e dans les titres de la presse alg\u00e9rienne lors de la candidature du pr\u00e9sident Abdelaziz Bouteflika. L\u2019auteure pr\u00e9sente aussi certains dispositifs de manifestation de la rumeur dans les discours journalistiques\u00a0: commentaires m\u00e9ta-discursifs, non-co\u00efncidences du dire, modalisations, n\u00e9gations pol\u00e9miques, etc.<\/p>\n\n\n\n<p><strong>La troisi\u00e8me partie<\/strong> intitul\u00e9e <em>Fake news et th\u00e9ories du complot<\/em> regroupe trois articles, traitant du rapport existant entre les informations fallacieuses et l\u2019imaginaire complotiste \/ conspirationniste.<\/p>\n\n\n\n<p>Dans <em>Le complot au fil des dictionnaires,<\/em> <strong>Rosa Cetro<\/strong> propose une \u00e9tude lexicographique diachronique du mot \u00ab complot \u00bb et de son synonyme \u00ab&nbsp;conspiration&nbsp;\u00bb, dans la soci\u00e9t\u00e9 fran\u00e7aise \u00e0 partir de l\u2019Ancien R\u00e9gime jusqu&#8217;\u00e0 la deuxi\u00e8me moitie du XX<sup>e<\/sup> si\u00e8cle, p\u00e9riode pendant laquelle <em>complot <\/em>et <em>conspiration<\/em> \u00ab&nbsp;se d\u00e9doublent&nbsp;\u00bb entre une acception technique, de nature juridique, et une acception g\u00e9n\u00e9rique. Avec l\u2019apparition des syntagmes \u00ab&nbsp;th\u00e9orie du complot&nbsp;\u00bb et \u00ab&nbsp;th\u00e9orie conspirationniste&nbsp;\u00bb, les deux mots enregistrent un \u00ab&nbsp;renversement de perspective&nbsp;\u00bb qui fait d\u00e9placer l\u2019acception du mot <em>complot<\/em> d\u2019une dimension priv\u00e9e et individuelle vers une dimension collective et globale.<\/p>\n\n\n\n<p><strong>Lorella Sini<\/strong> et <strong>Francesco Attruia<\/strong> (<em>\u00abLe Grand Remplacement \u00bb et la \u00ab sostituzione etnica \u00bb : th\u00e8ses complotistes et fake news dans les discours d\u2019extr\u00eame droite<\/em>) pr\u00e9sentent le code id\u00e9ologique alimentant les th\u00e9ories conspirationnistes autour d\u2019un <em>pr\u00e9tendu<\/em> dessein politique dont l\u2019objectif est le remplacement des populations europ\u00e9ennes \u00ab autochtones \u00bb par une immigration de masse programm\u00e9e. Il s\u2019agit d\u2019une analyse discursive et lexicale d\u2019un corpus fran\u00e7ais\/italien de discours politiques et de presse, qui met en \u00e9vidence la multiplicit\u00e9 des formes associ\u00e9es \u00e0 ces expressions, source de fake news alimentant les discours de haine.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le dernier article pr\u00e9sente la mythologie complotiste comme r\u00e9cit structurant, bipolarisant le monde. En effet, Cl\u00e9mentine Hougue<em> <\/em>(<em>Art du r\u00e9cit, figures et mythologie des fictions et discours complotistes<\/em>) offre la vision d\u2019un monde fig\u00e9 dans un \u00e9tat de pr\u00e9carit\u00e9 permanente o\u00f9 l\u2019individu a beau \u00eatre attentif aux signes du complot car il ne peut qu\u2019\u00eatre soumis au joug des forces structurant ce monde. Les th\u00e9ories du complot repr\u00e9sentent une impasse narrative, une intrigue sans r\u00e9solution, un r\u00e9cit boucl\u00e9 sur lui-m\u00eame car elles ne peuvent que rejouer ind\u00e9finiment l\u2019\u00e9tape de d\u00e9voilement du complot, sans lequel le monde retourne \u00e0 son incoh\u00e9rence.<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c0 la fin de notre parcours, il est \u00e9vident que les fake news, les rumeurs ou les intox\u00a0 pr\u00e9sentent des strat\u00e9gies et des vis\u00e9es discursives de d\u00e9sinformation ou de d\u00e9tournement d\u2019informations qui peuvent se manifester par une d\u00e9contextualisation syst\u00e9matique et un effacement des sources \u00e9nonciatives. Afin de contrecarrer tous ces effets n\u00e9gatifs, les contributions du volume mettent en exergue des proc\u00e9d\u00e9s discursifs finalis\u00e9s au renforcement de l\u2019\u00e9ducation aux m\u00e9dias \u00e0 une \u00e9valuation critique des sources d\u2019information.<\/h3>\n\n\n\n<h2 class=\"wp-block-heading\">&nbsp;[Daniela DINC\u0102]<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Rosa Cetro et Lorella Sini sont les deux coordinatrices du volume Fake news, rumeurs, intox\u2026 Strat\u00e9gies et vis\u00e9es discursives de la d\u00e9sinformation paru chez L\u2019Harmattan et publi\u00e9 dans la collection Humanit\u00e9s Num\u00e9riques, avec le soutien de plusieurs organismes\u00a0: LIDILEM, Universit\u00e9 Franco-Italienne, Universit\u00e0 di Pisa \u2013 Dipartimento di Filologia, Letteratura e Linguistica et Do.Ri.F Universit\u00e0. Les\u2026 <span class=\"read-more\"><a href=\"http:\/\/www.farum.it\/lectures\/2021\/06\/29\/lorella-sini-rosa-cetro-eds-fake-news-rumeurs-intox-strategies-et-visees-discursives-de-la-desinformation-paris-lharmattan-2020-p-326\/\">Leggi tutto &raquo;<\/a><\/span><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-277","post","type-post","status-publish","format-standard","hentry","category-n-43"],"_links":{"self":[{"href":"http:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/posts\/277"}],"collection":[{"href":"http:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/comments?post=277"}],"version-history":[{"count":2,"href":"http:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/posts\/277\/revisions"}],"predecessor-version":[{"id":332,"href":"http:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/posts\/277\/revisions\/332"}],"wp:attachment":[{"href":"http:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/media?parent=277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/categories?post=277"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.farum.it\/lectures\/wp-json\/wp\/v2\/tags?post=277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}